{"id":2431,"date":"2021-05-24T13:17:37","date_gmt":"2021-05-24T11:17:37","guid":{"rendered":"https:\/\/iquord.eu\/sin-categorizar\/presentacion-iquord\/"},"modified":"2021-05-24T13:17:37","modified_gmt":"2021-05-24T11:17:37","slug":"presentacion-iquord","status":"publish","type":"post","link":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/","title":{"rendered":"Presentaci\u00f3n iQUORD"},"content":{"rendered":"<p>Despu\u00e9s de 12 a\u00f1os en el sector, damos un valiente paso al frente para seguir liderando la transformaci\u00f3n energ\u00e9tica hacia un nuevo modelo de negocio.<\/p>\n<p>Para ello, no s\u00f3lo innovamos en nuestro trabajo, tambi\u00e9n lo hacemos en nuestra marca y presentamos Iquord. Bajo este nuevo nombre queremos seguir acompa\u00f1ando a nuestros socios a alcanzar sus metas de adaptaci\u00f3n energ\u00e9tica, con seguridad y tranquilidad en un entorno cambiante.<\/p>\n<p>Iquord tiene el mismo ADN innovador y seguiremos apostando por la inversi\u00f3n en las \u00faltimas tecnolog\u00edas que nos lleven a estar en primera fila en la nueva revoluci\u00f3n energ\u00e9tica.<\/p>\n<p>Nos gusta escuchar todas las ideas de las partes implicadas, ya que entendemos la escucha activa como motor de cambio. Esto nos permite compartir conocimientos para tomar las mejores decisiones, establecer relaciones permanentes y desarrollar una confianza mutua. Mejoramos los resultados a partir de los objetivos de cada proyecto, y lo hacemos de forma que el desarrollo econ\u00f3mico, social y medioambiental sea equitativo.<\/p>\n<p>Nuestra compa\u00f1\u00eda seguir\u00e1 liderando el mercado eHouse con una soluci\u00f3n plug and play para alojar equipos el\u00e9ctricos de potencia y control que proporciona un suministro de energ\u00eda r\u00e1pida y fiable. Una tecnolog\u00eda vanguardista que ser\u00e1 una de las protagonistas en esta transformaci\u00f3n energ\u00e9tica. Estamos convencidos de las posibilidades y mejoras que nos puede aportar a todos en nuestra vida diaria.<\/p>\n<p>De la misma manera, queremos ser protagonistas en el mercado de las energ\u00edas renovables, que va a tomar una relevancia especial en los pr\u00f3ximos a\u00f1os de esta transformaci\u00f3n energ\u00e9tica. Hemos hecho un gran esfuerzo para desarrollar esta l\u00ednea de negocio en nuestra empresa y hemos realizado varios proyectos importantes y de envergadura en los \u00faltimos a\u00f1os que demuestran que vamos por el buen camino.<\/p>\n<p>Nuestra promesa de marca es Dreams plugged in, conseguir que las ideas de nuestros clientes se hagan realidad y de una forma que est\u00e9n integradas en la nueva transici\u00f3n a una nueva era.<\/p>\n<p>La implicaci\u00f3n integral en todas las fases del proyecto y el trato cercano con nuestros clientes marcar\u00e1n la diferencia.<\/p>\n<p>Por \u00faltimo, nos gustar\u00eda destacar el excelente grupo humano que seguir\u00e1 formando parte de la empresa, ahora como Iquord, y tanto de sus valores, como de su desempe\u00f1o en los proyectos que realizan y en el apoyo t\u00e9cnico que les dan a las empresas con las que trabajamos. Son el componente m\u00e1s importante para nosotros y crean el valor a\u00f1adido que resulta clave en un mercado tan din\u00e1mico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de 12 a\u00f1os en el sector, damos un valiente  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":2436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.4 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Presentaci\u00f3n iQUORD - iQUORD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci\u00f3n iQUORD\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de 12 a\u00f1os en el sector, damos un valiente paso al frente para seguir liderando la transformaci\u00f3n energ\u00e9tica hacia un nuevo modelo de negocio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/\" \/>\n<meta property=\"og:site_name\" content=\"iQUORD\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-24T11:17:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Gutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Gutierrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/\"},\"author\":{\"name\":\"David Gutierrez\",\"@id\":\"https:\/\/iquord.eu\/es\/#\/schema\/person\/f84eea7143c1319e3d8ccf0bbb6c9e80\"},\"headline\":\"Presentaci\u00f3n iQUORD\",\"datePublished\":\"2021-05-24T11:17:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/\"},\"wordCount\":444,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/iquord.eu\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/\",\"url\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/\",\"name\":\"Presentaci\u00f3n iQUORD - iQUORD\",\"isPartOf\":{\"@id\":\"https:\/\/iquord.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg\",\"datePublished\":\"2021-05-24T11:17:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage\",\"url\":\"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg\",\"contentUrl\":\"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/iquord.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaci\u00f3n iQUORD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/iquord.eu\/es\/#website\",\"url\":\"https:\/\/iquord.eu\/es\/\",\"name\":\"iQUORD\",\"description\":\"Dreams plugged in\",\"publisher\":{\"@id\":\"https:\/\/iquord.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/iquord.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/iquord.eu\/es\/#organization\",\"name\":\"iQUORD\",\"url\":\"https:\/\/iquord.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/iquord.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/02\/logotipo_sticky_x1-1.png\",\"contentUrl\":\"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/02\/logotipo_sticky_x1-1.png\",\"width\":150,\"height\":28,\"caption\":\"iQUORD\"},\"image\":{\"@id\":\"https:\/\/iquord.eu\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/iquord\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/iquord.eu\/es\/#\/schema\/person\/f84eea7143c1319e3d8ccf0bbb6c9e80\",\"name\":\"David Gutierrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/iquord.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05fe3b25828b931998c8b71828fe970bd40a8a698f78c7cbd2e4b52dd57e8e7f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05fe3b25828b931998c8b71828fe970bd40a8a698f78c7cbd2e4b52dd57e8e7f?s=96&d=mm&r=g\",\"caption\":\"David Gutierrez\"},\"url\":\"https:\/\/iquord.eu\/es\/author\/davidgutierrez\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Presentaci\u00f3n iQUORD - iQUORD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaci\u00f3n iQUORD","og_description":"Despu\u00e9s de 12 a\u00f1os en el sector, damos un valiente paso al frente para seguir liderando la transformaci\u00f3n energ\u00e9tica hacia un nuevo modelo de negocio.","og_url":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/","og_site_name":"iQUORD","article_published_time":"2021-05-24T11:17:37+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg","type":"image\/jpeg"}],"author":"David Gutierrez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David Gutierrez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#article","isPartOf":{"@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/"},"author":{"name":"David Gutierrez","@id":"https:\/\/iquord.eu\/es\/#\/schema\/person\/f84eea7143c1319e3d8ccf0bbb6c9e80"},"headline":"Presentaci\u00f3n iQUORD","datePublished":"2021-05-24T11:17:37+00:00","mainEntityOfPage":{"@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/"},"wordCount":444,"commentCount":0,"publisher":{"@id":"https:\/\/iquord.eu\/es\/#organization"},"image":{"@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage"},"thumbnailUrl":"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg","articleSection":["General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/","url":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/","name":"Presentaci\u00f3n iQUORD - iQUORD","isPartOf":{"@id":"https:\/\/iquord.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage"},"image":{"@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage"},"thumbnailUrl":"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg","datePublished":"2021-05-24T11:17:37+00:00","breadcrumb":{"@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#primaryimage","url":"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg","contentUrl":"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/05\/presentacion-iquord.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/iquord.eu\/es\/general\/presentacion-iquord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iquord.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Presentaci\u00f3n iQUORD"}]},{"@type":"WebSite","@id":"https:\/\/iquord.eu\/es\/#website","url":"https:\/\/iquord.eu\/es\/","name":"iQUORD","description":"Dreams plugged in","publisher":{"@id":"https:\/\/iquord.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iquord.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/iquord.eu\/es\/#organization","name":"iQUORD","url":"https:\/\/iquord.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iquord.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/02\/logotipo_sticky_x1-1.png","contentUrl":"https:\/\/iquord.eu\/wp-content\/uploads\/2021\/02\/logotipo_sticky_x1-1.png","width":150,"height":28,"caption":"iQUORD"},"image":{"@id":"https:\/\/iquord.eu\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/iquord\/"]},{"@type":"Person","@id":"https:\/\/iquord.eu\/es\/#\/schema\/person\/f84eea7143c1319e3d8ccf0bbb6c9e80","name":"David Gutierrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iquord.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05fe3b25828b931998c8b71828fe970bd40a8a698f78c7cbd2e4b52dd57e8e7f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05fe3b25828b931998c8b71828fe970bd40a8a698f78c7cbd2e4b52dd57e8e7f?s=96&d=mm&r=g","caption":"David Gutierrez"},"url":"https:\/\/iquord.eu\/es\/author\/davidgutierrez\/"}]}},"_links":{"self":[{"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/posts\/2431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/comments?post=2431"}],"version-history":[{"count":0,"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/posts\/2431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/media\/2436"}],"wp:attachment":[{"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/media?parent=2431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/categories?post=2431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iquord.eu\/es\/wp-json\/wp\/v2\/tags?post=2431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}